{"id":1281,"date":"2018-09-01T10:13:07","date_gmt":"2018-09-01T10:13:07","guid":{"rendered":"https:\/\/www.ascensoresbalaguer.com\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/"},"modified":"2021-02-03T22:33:10","modified_gmt":"2021-02-03T22:33:10","slug":"instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses","status":"publish","type":"post","link":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/","title":{"rendered":"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses"},"content":{"rendered":"<p>El Consejo Superior de la Judicatura, seccional Valle del Cauca, emiti\u00f3 un plan de contingencia con el cual se espera la apertura del Palacio de Justicia de Cali en 10 meses.<\/p>\n<p>Esto se da tras la tragedia ocurrida el pasado 15 de agosto de 2018 cuando un ascensor se desplom\u00f3 del sexto piso del ese edificio dejando como saldo dos personas muertas y cuatro m\u00e1s heridas, <strong>motivo por el cual funcionarios de Asonal Judicial se negaron a prestar el servicio.<\/strong><\/p>\n<p><strong>Y es que en los 15 d\u00edas que han estado cerrados los despachos judiciales hay m\u00e1s de 34.000 procesos represados y de los cuales no se han podido dar tr\u00e1mite<\/strong>, siendo las tutelas las que m\u00e1s preocupan.<\/p>\n<p>Solamente los juzgados de familia tienen m\u00e1s de 3.800 procesos pendientes, los juzgados civiles 6.200 y los dem\u00e1s juzgados cerca de 16.000.<\/p>\n<p>Ante esto se realiz\u00f3 una investigaci\u00f3n entre las autoridades de la Polic\u00eda y una firma que revis\u00f3 el estado de los ascensores del Palacio y que, <strong>seg\u00fan el concepto t\u00e9cnico, se debe suspender el uso de los seis elevadores y comprar unos nuevos.<\/strong><\/p>\n<p>Este proceso durar\u00e1 por lo menos 10 meses tras la autorizaci\u00f3n de la compra de tres ascensores a trav\u00e9s del acuerdo PCSJA18-11079 del 24 de Agosto de 2018, en donde se autoriz\u00f3 al Director Ejecutivo Nacional para adelantar el proceso de contrataci\u00f3n que permita la compra de los ascensores.<\/p>\n<p><strong>En total son 610 millones de pesos para comprarlos y 43 millones para realizar la interventor\u00eda t\u00e9cnica, econ\u00f3mica y financiera.<\/strong><\/p>\n<p>Ante esto se vio necesario que los empleados de la rama judicial reactiven sus labores por lo que se habilitar\u00e1n, como parte de la soluci\u00f3n transitoria, reactivar los 149 despachos.<\/p>\n<p>Sin embargo, esta reactivaci\u00f3n har\u00e1 que se abran nuevamente los 17 pisos del Palacio de Justicia, los cuales deber\u00e1n ser subidos y bajados por las escaleras.<\/p>\n<p>Este tipo de noticias, son una buena excusa para revisar la propia\u00a0<a href=\"https:\/\/www.ascensoresbalaguer.com\/co\/servicios\/instalacion-de-ascensores\/\"><strong>instalaci\u00f3n de ascensor<\/strong><\/a>. Somos usuarios habituales de elevadores y plataformas, y muchas veces ni nos cuestionamos sobre su funcionamiento y\u00a0<strong><a href=\"https:\/\/www.ascensoresbalaguer.com\/co\/servicios\/mantenimiento-y-reparaciones\/\">mantenimiento<\/a><\/strong>.<\/p>\n<p><strong>En Ascensores Balaguer, contamos con el precio mas bajo del mercado! El l\u00edder europeo, con m\u00e1s de 20 a\u00f1os de experiencia a llegado a Colombia.\u00a0<a href=\"https:\/\/www.ascensoresbalaguer.com\/co\/contacto\/\">Contacte hoy mismo<\/a>\u00a0con nosotros!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Superior de la Judicatura, seccional Valle del Cauca, emiti\u00f3 un plan de contingencia con el cual se espera la apertura del Palacio de Justicia de Cali en 10 meses.<\/p>\n","protected":false},"author":4,"featured_media":1279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[]},"categories":[18],"tags":[],"class_list":["post-1281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ascensores-co","category-18","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.2 (Yoast SEO v25.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses - Ascensores Balaguer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses\" \/>\n<meta property=\"og:description\" content=\"El Consejo Superior de la Judicatura, seccional Valle del Cauca, emiti\u00f3 un plan de contingencia con el cual se espera la apertura del Palacio de Justicia de Cali en 10 meses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\" \/>\n<meta property=\"og:site_name\" content=\"Ascensores Balaguer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ascensors.Balaguer.Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-01T10:13:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-03T22:33:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Damian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\"},\"author\":{\"name\":\"Damian\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/person\/c6f0c6d4e1e0d13b1a7b8ccd2008245a\"},\"headline\":\"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses\",\"datePublished\":\"2018-09-01T10:13:07+00:00\",\"dateModified\":\"2021-02-03T22:33:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\"},\"wordCount\":394,\"publisher\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg\",\"articleSection\":[\"Ascensores\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\",\"url\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\",\"name\":\"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses - Ascensores Balaguer\",\"isPartOf\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg\",\"datePublished\":\"2018-09-01T10:13:07+00:00\",\"dateModified\":\"2021-02-03T22:33:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage\",\"url\":\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg\",\"contentUrl\":\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg\",\"width\":650,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.ascensoresbalaguer.com\/co\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#website\",\"url\":\"https:\/\/www.ascensoresbalaguer.com\/co\/\",\"name\":\"Ascensores Balaguer\",\"description\":\"Especialistas en Espacios Reducidos\",\"publisher\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ascensoresbalaguer.com\/co\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#organization\",\"name\":\"Ascensores Balaguer\",\"url\":\"https:\/\/www.ascensoresbalaguer.com\/co\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2015\/07\/logo-mini.png\",\"contentUrl\":\"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2015\/07\/logo-mini.png\",\"width\":113,\"height\":111,\"caption\":\"Ascensores Balaguer\"},\"image\":{\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Ascensors.Balaguer.Barcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/person\/c6f0c6d4e1e0d13b1a7b8ccd2008245a\",\"name\":\"Damian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b63fbe5ddeca8b51b7fe973bcc2c2f4ba93f8e7802e5251a7284d051a700d5f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b63fbe5ddeca8b51b7fe973bcc2c2f4ba93f8e7802e5251a7284d051a700d5f1?s=96&d=mm&r=g\",\"caption\":\"Damian\"},\"url\":\"https:\/\/www.ascensoresbalaguer.com\/co\/author\/ekualia\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses - Ascensores Balaguer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/","og_locale":"es_ES","og_type":"article","og_title":"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses","og_description":"El Consejo Superior de la Judicatura, seccional Valle del Cauca, emiti\u00f3 un plan de contingencia con el cual se espera la apertura del Palacio de Justicia de Cali en 10 meses.","og_url":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/","og_site_name":"Ascensores Balaguer","article_publisher":"https:\/\/www.facebook.com\/Ascensors.Balaguer.Barcelona","article_published_time":"2018-09-01T10:13:07+00:00","article_modified_time":"2021-02-03T22:33:10+00:00","og_image":[{"width":650,"height":466,"url":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg","type":"image\/jpeg"}],"author":"Damian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Damian","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#article","isPartOf":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/"},"author":{"name":"Damian","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/person\/c6f0c6d4e1e0d13b1a7b8ccd2008245a"},"headline":"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses","datePublished":"2018-09-01T10:13:07+00:00","dateModified":"2021-02-03T22:33:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/"},"wordCount":394,"publisher":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#organization"},"image":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg","articleSection":["Ascensores"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/","url":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/","name":"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses - Ascensores Balaguer","isPartOf":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage"},"image":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg","datePublished":"2018-09-01T10:13:07+00:00","dateModified":"2021-02-03T22:33:10+00:00","breadcrumb":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#primaryimage","url":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg","contentUrl":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2018\/09\/blu_radio_ascensores_del_palacio_de_jusiticia_de_cali-2.jpg","width":650,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/instalacion-de-nuevos-ascensores-en-el-palacio-de-justicia-de-cali-tardara-10-meses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ascensoresbalaguer.com\/co\/"},{"@type":"ListItem","position":2,"name":"Instalaci\u00f3n de nuevos ascensores en el Palacio de Justicia de Cali tardar\u00e1 10 meses"}]},{"@type":"WebSite","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#website","url":"https:\/\/www.ascensoresbalaguer.com\/co\/","name":"Ascensores Balaguer","description":"Especialistas en Espacios Reducidos","publisher":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ascensoresbalaguer.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#organization","name":"Ascensores Balaguer","url":"https:\/\/www.ascensoresbalaguer.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2015\/07\/logo-mini.png","contentUrl":"https:\/\/www.ascensoresbalaguer.com\/wp-content\/uploads\/2015\/07\/logo-mini.png","width":113,"height":111,"caption":"Ascensores Balaguer"},"image":{"@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ascensors.Balaguer.Barcelona"]},{"@type":"Person","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/person\/c6f0c6d4e1e0d13b1a7b8ccd2008245a","name":"Damian","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.ascensoresbalaguer.com\/co\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b63fbe5ddeca8b51b7fe973bcc2c2f4ba93f8e7802e5251a7284d051a700d5f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63fbe5ddeca8b51b7fe973bcc2c2f4ba93f8e7802e5251a7284d051a700d5f1?s=96&d=mm&r=g","caption":"Damian"},"url":"https:\/\/www.ascensoresbalaguer.com\/co\/author\/ekualia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/posts\/1281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/comments?post=1281"}],"version-history":[{"count":1,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/posts\/1281\/revisions"}],"predecessor-version":[{"id":3108,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/posts\/1281\/revisions\/3108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/media\/1279"}],"wp:attachment":[{"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/media?parent=1281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/categories?post=1281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ascensoresbalaguer.com\/co\/wp-json\/wp\/v2\/tags?post=1281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}